{"id":184,"count":1,"description":"","link":"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/","name":"Massage Tool","slug":"massage-tool-nl","taxonomy":"product_cat","parent":179,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Massage Tool - Combray Skin Care<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Massage Tool - Combray Skin Care\" \/>\n<meta property=\"og:url\" content=\"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/\" \/>\n<meta property=\"og:site_name\" content=\"Combray Skin Care\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/\",\"url\":\"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/\",\"name\":\"Massage Tool - Combray Skin Care\",\"isPartOf\":{\"@id\":\"https:\/\/combray-skincare.com\/nl\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/combray-skincare.com\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accessoires\",\"item\":\"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Massage Tool\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/combray-skincare.com\/nl\/#website\",\"url\":\"https:\/\/combray-skincare.com\/nl\/\",\"name\":\"Combray Skin Care\",\"description\":\"Combray is skin care product with only two ingredients. Containing a patented antioxidant and a 100% natural oil. It is designed to mimic and supplement the skin's own protection methods.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/combray-skincare.com\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Massage Tool - Combray Skin Care","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/","og_locale":"nl_NL","og_type":"article","og_title":"Massage Tool - Combray Skin Care","og_url":"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/","og_site_name":"Combray Skin Care","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/","url":"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/","name":"Massage Tool - Combray Skin Care","isPartOf":{"@id":"https:\/\/combray-skincare.com\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/massage-tool-nl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/combray-skincare.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Accessoires","item":"https:\/\/combray-skincare.com\/nl\/product-category\/accessoires\/"},{"@type":"ListItem","position":3,"name":"Massage Tool"}]},{"@type":"WebSite","@id":"https:\/\/combray-skincare.com\/nl\/#website","url":"https:\/\/combray-skincare.com\/nl\/","name":"Combray Skin Care","description":"Combray is skin care product with only two ingredients. Containing a patented antioxidant and a 100% natural oil. It is designed to mimic and supplement the skin's own protection methods.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/combray-skincare.com\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/combray-skincare.com\/nl\/wp-json\/wp\/v2\/product_cat\/184"}],"collection":[{"href":"https:\/\/combray-skincare.com\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/combray-skincare.com\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/combray-skincare.com\/nl\/wp-json\/wp\/v2\/product_cat\/179"}],"wp:post_type":[{"href":"https:\/\/combray-skincare.com\/nl\/wp-json\/wp\/v3\/product?product_cat=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}